{"id":1751,"date":"1997-02-09T16:21:49","date_gmt":"1997-02-09T15:21:49","guid":{"rendered":"https:\/\/www.ac-am.fr\/?p=1751"},"modified":"2026-02-15T21:32:52","modified_gmt":"2026-02-15T20:32:52","slug":"la-crise-suicidaire","status":"publish","type":"post","link":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/","title":{"rendered":"La Crise Suicidaire&#8230;"},"content":{"rendered":"<div style=\"background-image: url('\/wp-content\/uploads\/2025\/08\/gra_jaun.gif'); background-attachment: fixed; border: 2px solid #000000; border-radius: 20px; opacity: 0.90;\">\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_rd.gif\" alt=\"barre rouge\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-23441af8 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/11\/retemort.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"100\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/11\/retemort.gif\" alt=\"Titre r\u00e9flexion et t\u00e9moignage face \u00e0 sa mort\" class=\"wp-image-1733\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/cal1997.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/cal1997.gif\" alt=\"Calendrier ann\u00e9e 1997\" class=\"wp-image-221\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_rd.gif\" alt=\"barre rouge\"\/><\/figure>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/balle02.gif\" alt=\"\"> J&rsquo;ai moi-m\u00eame connu le <a href=\"https:\/\/www.ac-am.fr\/index.php\/1996\/06\/29\/france-nous-parle\/\">d\u00e9sir ardent de me suicider<\/a> et j&rsquo;ai longtemps tent\u00e9 de le faire consciemment et inconsciemment. Mais j&rsquo;ai vaincu cette propension et aid\u00e9 plusieurs jeunes suicidaires. Mes exp\u00e9riences m&rsquo;ont amen\u00e9 \u00e0 la conclusion suivante: <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">LES PENS\u00c9ES SUICIDAIRES N&rsquo;APPARTIENNENT G\u00c9N\u00c9RALEMENT PAS \u00c0 CEUX QUI LES VIVENT ET QUI EN DEVIENNENT LES VICTIMES<\/mark>. Dans bien des cas, il s&rsquo;agit souvent d&rsquo;influences n\u00e9gatives qui tirent profit des faiblesses, des peurs et des souffrances des \u00eatres humains. Souvent on entend un rescap\u00e9 du suicide s&rsquo;exclamer: \u00ab\u00a0Je ne comprends pas ce qui m&rsquo;a pris !\u00a0\u00bb, ou \u00ab\u00a0Je n&rsquo;avais plus d&rsquo;espoir en la vie, je ne voyais pas la lumi\u00e8re au bout du tunnel\u00a0\u00bb, ou \u00ab\u00a0La seule chose que je pouvais envisager, c&rsquo;\u00e9tait le suicide. Je ne pouvais contr\u00f4ler cette pens\u00e9e\u00a0\u00bb, ou bien encore \u00ab\u00a0Quelque chose ou quelqu&rsquo;un me disait de me suicider\u00a0\u00bb. Ces impulsions proviennent g\u00e9n\u00e9ralement d&rsquo;une \u00e9nergie n\u00e9gative cr\u00e9\u00e9e par les formes pens\u00e9es de la personne elle-m\u00eame. Elles peuvent aussi r\u00e9sulter de l&rsquo;influence d&rsquo;entit\u00e9s d\u00e9sincarn\u00e9es, soit d&rsquo;\u00eatres humains qui se sont eux-m\u00eames suicid\u00e9s, croyant que c&rsquo;\u00e9tait la meilleure solution \u00e0 leurs probl\u00e8mes. De plus, l&rsquo;alcool, les drogues et les fausses croyances amplifi\u00e9es par la soci\u00e9t\u00e9 affaiblissent certaines personnes, les rendant encore plus vuln\u00e9rables au suicide. Elles deviennent des victimes dociles. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L&rsquo;ALCOOL ET LES DROGUES ONT \u00c9T\u00c9 INTRODUITS DANS LA SOCI\u00c9T\u00c9 POUR VOUS FAIRE PERDRE VOS POUVOIRS, POUR VOUS AFFAIBLIR ET VOUS CONTR\u00d4LER, ET VOYEZ \u00c0 QUI CELA PROFITE; ARGENT, CONTR\u00d4LE ET POUVOIR<\/mark>. Il arrive parfois que certains membres d&rsquo;une famille ou des amis qui se sont suicid\u00e9s hantent leurs connaissances, les incitant au suicide afin de les retrouver. Tout ceci est grandement facilit\u00e9 par l&rsquo;absorption d&rsquo;alcool et de drogues, car ces facteurs alt\u00e8rent la conscience et ouvrent la porte \u00e0 toutes sortes d&rsquo;\u00e9nergies discordantes. Les personnes \u00e0 tendance suicidaire auraient tout int\u00e9r\u00eat \u00e0 discerner les sources de la pers\u00e9cution qu&rsquo;elles subissent. Vous avez peut-\u00eatre remarqu\u00e9 que la majorit\u00e9 des candidats au suicide sont des personnes qui poss\u00e8dent une grande sensibilit\u00e9 \u00e9motionnelle et une intelligence plus d\u00e9velopp\u00e9e, ou sup\u00e9rieure, bien qu&rsquo;inexploit\u00e9e. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">VOTRE DEGR\u00c9 DE SOUFFRANCE EST PROPORTIONNEL \u00c0 VOTRE POUVOIR, OU \u00c0 VOS CAPACIT\u00c9S<\/mark>. Donc si vous souffrez \u00e9norm\u00e9ment, c&rsquo;est que vous \u00eates tr\u00e8s puissant. Les gens puissants souffrent <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">D&rsquo;AVANTAGE ET AVEC PLUS D&rsquo;INTENSIT\u00c9<\/mark>. Un entourage discordant et des situations conflictuelles les affecteront plus profond\u00e9ment, et par cons\u00e9quent, leur d\u00e9ception pendra plus d&rsquo;ampleur. Ces jeunes seront plus touch\u00e9s par l&rsquo;\u00e9tat actuel de l&rsquo;environnement et de la soci\u00e9t\u00e9, et leur sens de la justice sera plus conscient et d\u00e9fini. On les entendra souvent dire: \u00ab\u00a0Ce n&rsquo;est pas juste !\u00a0\u00bb, ou \u00ab\u00a0Je n&rsquo;ai pas d&rsquo;avenir\u00a0\u00bb, ou \u00ab\u00a0Je n&rsquo;en peux plus, \u00c7a n&rsquo;a pas d&rsquo;allure\u00a0\u00bb. \u00c0 ce propos, je vous dirai que <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">PLUS LES \u00c9L\u00c9MENTS N\u00c9GATIFS SONT PUISSANTS, PLUS LES \u00c9L\u00c9MENTS POSITIFS LE SONT \u00c9GALEMENT<\/mark>.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/balle02.gif\" alt=\"\"> Laissez-moi vous relater le cas d&rsquo;une jeune fille de 16 ans qui avait compl\u00e8tement perdu le go\u00fbt de vivre et d&rsquo;apprendre \u00e0 utiliser sa cr\u00e9ativit\u00e9; elle ne parvenait pas \u00e0 s&rsquo;imaginer un futur int\u00e9ressant. Apr\u00e8s avoir discut\u00e9 avec elle, je me suis rendu compte qu&rsquo;elle \u00e9tait s\u00e9rieusement et dangereusement suicidaire, sans qu&rsquo;elle le r\u00e9alise vraiment. Je voyais qu&rsquo;elle se laissait inconsciemment manipuler par des entit\u00e9s, soit des amis qui s&rsquo;\u00e9taient suicid\u00e9s r\u00e9cemment. Je lui ai donc demand\u00e9 de me raconter ses r\u00eaves. L&rsquo;un d&rsquo;eux r\u00e9v\u00e9la des \u00e9vidences significatives quant \u00e0 ce qui a \u00e9t\u00e9 dit pr\u00e9c\u00e9demment. Durant la nuit, sa chambre et son salon furent envahis par des jeunes de son \u00e2ge, parmi lesquels elle reconnut des amis qui s&rsquo;\u00e9taient suicid\u00e9s. Elle les voyait consommer de l&rsquo;alcool et de la drogue, et faire des allusions aux plaisirs sexuels. Ils lui r\u00e9p\u00e9taient sans cesse: \u00ab\u00a0Viens f\u00eater avec nous! Viens nous rejoindre, vois comme nous nous amusons!\u00a0\u00bb, ou \u00ab\u00a0Viens rejoindre tes amis. Nous avons fait la bonne chose, le bon choix. Nous avons eu le courage de le faire.\u00a0\u00bb Par la suite ces pens\u00e9es la hantaient constamment, mais elle ne s&rsquo;en rendait pas compte. Apr\u00e8s un \u00e9change plut\u00f4t ardu, je lui ai fait prendre conscience de l&#8217;emprise que ces entit\u00e9s exer\u00e7aient sur elle tout en lui montrant que son attitude suicidaire \u00e9tait une cons\u00e9quence directe de cette influence. Elle comprit les motivations malsaines cach\u00e9es derri\u00e8re ces pens\u00e9es. Elle d\u00e9couvrit qu&rsquo;elle avait le pouvoir de contr\u00f4ler sa pens\u00e9e, de discerner \u00ab\u00a0leurs\u00a0\u00bb pens\u00e9es des siennes, et de les tenir \u00e0 distance. D\u00e8s le lendemain elle avait repris le go\u00fbt \u00e0 la vie de fa\u00e7on inesp\u00e9r\u00e9e. Elle a pu ensuite cr\u00e9\u00e9 de tr\u00e8s beaux projets. Maintenant elle se fixe r\u00e9guli\u00e8rement de nouveaux buts qu&rsquo;elle r\u00e9alise, car elle croit d\u00e9sormais en ses aptitudes. Cela est devenu possible parce qu&rsquo;elle contr\u00f4le ses pens\u00e9es et qu&rsquo;elle a repris confiance en sa propre cr\u00e9ativit\u00e9. Mais surtout, elle est maintenant consciente que son v\u00e9ritable objectif personnel, et les fa\u00e7ons d&rsquo;y parvenir, n&rsquo;ont absolument rien \u00e0 voir avec le suicide.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/balle02.gif\" alt=\"\"> Beaucoup d&rsquo;adolescents consomment de la drogue et de l&rsquo;alcool. Plus les doses et la fr\u00e9quence de consommation augmentent, plus ils perdent le contr\u00f4le de leurs facult\u00e9s et deviennent dysfonctionnels, en proie a une n\u00e9gativit\u00e9 et \u00e0 une violence tourn\u00e9es contre eux-m\u00eames ou les autres. La criminalit\u00e9 et les actes de violences des adolescents sont des cris d&rsquo;alarme et de contestation. Naturellement, les jeunes disent: \u00ab\u00a0C&rsquo;est la faute de la soci\u00e9t\u00e9, des parents, des autres\u2026\u00a0\u00bb Sachez que ceci n&rsquo;est pas enti\u00e8rement faux, car <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">IL EST DIFFICILE D&rsquo;ACCEPTER CERTAINES SITUATIONS LORSQU&rsquo;ON LES PER\u00c7OIT AVEC PERSPICACIT\u00c9, DE FA\u00c7ON PLUS CONSCIENTE<\/mark>. Car les adultes acceptent un quotidien \u00e9rig\u00e9 sur des concepts pr\u00e9\u00e9tablis qu&rsquo;ils ne questionnent jamais. Bien s\u00fbr, ils grognent de temps en temps, mais la routine quotidienne ram\u00e8ne rapidement tout en \u00ab\u00a0ordre\u00a0\u00bb. Comprenez qu&rsquo;il est difficile \u00e0 ces gar\u00e7ons et \u00e0 ces filles, dont le niveau de conscience est plus \u00e9lev\u00e9 que celui du cercle familial ou des amis, d&rsquo;observer et d&rsquo;accepter ce qui se passe autour d&rsquo;eux. Plus leur souffrance est intense, plus ils rejettent la soci\u00e9t\u00e9. C&rsquo;est pourquoi on les entend parfois s&rsquo;\u00e9crier: \u00ab\u00a0Je ne veux plus vivre dans cette soci\u00e9t\u00e9!\u00a0\u00bb, ou \u00ab\u00a0Je ne peux pas accepter ce qui se passe!\u00a0\u00bb, ou \u00ab\u00a0Vous n&rsquo;\u00eates pas comme moi, vous ne pouvez pas me comprendre\u00a0\u00bb. Alors, ils d\u00e9crochent physiquement ou mentalement, ou bien les deux \u00e0 la fois. Si les jeunes comprennent <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">QUI ILS SONT VRAIMENT<\/mark>, s&rsquo;ils reconnaissent les raisons de leur r\u00e9bellion et de leur souffrance, s&rsquo;ils prennent conscience du <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">POUVOIR QUE LEURS PENS\u00c9ES POSITIVES OU N\u00c9GATIVES ONT SUR EUX<\/mark>, s&rsquo;ils savent comment contr\u00f4ler et transformer leurs pens\u00e9es, alors, leurs d\u00e9sirs et leurs souffrances deviendront des sources d&rsquo;inspiration pour cr\u00e9er de nouveau.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/balle02.gif\" alt=\"\"> Il est important aussi de noter que les personnes qui ont exp\u00e9riment\u00e9 un abus quelconque (physique, intellectuel, \u00e9motif ou mental) ont ainsi cr\u00e9\u00e9 des formes pens\u00e9es qui peuvent les maintenir dans des croyances n\u00e9gatives, dans la souffrance et la peur. Ces personnes peuvent inconsciemment l\u00e9guer leur pouvoir \u00e0 ces aspects n\u00e9gatifs d&rsquo;eux-m\u00eames qui les accableront jusqu&rsquo;\u00e0 ce qu&rsquo;elles d\u00e9cident consciemment d&rsquo;y mettre un terme. L&rsquo;inconscience par rapport \u00e0 l&rsquo;influence des pens\u00e9es n\u00e9gatives peut se r\u00e9sumer dans des propos: \u00ab\u00a0Je ne sais pas pourquoi je pense comme \u00e7a\u00a0\u00bb, ou \u00ab\u00a0J&rsquo;ai toujours telle impression\u00a0\u00bb, ou \u00ab\u00a0Cette pens\u00e9e revient constamment sans que je sache pourquoi\u00a0\u00bb, ou \u00ab\u00a0Quelqu&rsquo;un me dit toujours\u2026\u00a0\u00bb, ou encore \u00ab\u00a0J&rsquo;ai compl\u00e8tement oubli\u00e9 telle ou telle p\u00e9riode de ma vie. Je n&rsquo;en garde aucun souvenir.\u00a0\u00bb<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/balle02.gif\" alt=\"\"> En somme, ce qui importe, c&rsquo;est de savoir que si vous <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">NE COMPRENEZ PAS CE QUI VOUS ARRIVE, C&rsquo;EST QUE VOTRE SYST\u00c8ME DE PENS\u00c9E EST INAD\u00c9QUAT, SUBJUGU\u00c9 PAR DIFF\u00c9RENTES INFLUENCES INCONSCIENTES<\/mark>. Tous les probl\u00e8mes ont des solutions, mais pour d\u00e9couvrir les diverses possibilit\u00e9s existantes, on doit d&rsquo;abord sortir de l&rsquo;inconscience et de l&rsquo;ignorance.<\/p>\n\n\n\n<p>[<em><a href=\"https:\/\/www.ac-am.fr\/index.php\/contact-acam\/\">Micha\u00ebl AR. &#8211; le 09-02-97<\/a><\/em>]<\/p>\n\n\n<\/div><div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"big\";var hupso_image_folder_url = \"\";var hupso_url_t=\"\";var hupso_title_t=\"La%20Crise%20Suicidaire...\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai moi-m\u00eame connu le d\u00e9sir ardent de me suicider et j&rsquo;ai longtemps tent\u00e9 de le&#8230;<\/p>\n","protected":false},"author":33,"featured_media":5392,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196],"tags":[1957,1959,1955,1958,1960,1954,1956,1961,1963,1962],"class_list":["post-1751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1997-mort","tag-energie-negative","tag-entites-desincarnees","tag-etres-humains","tag-formes-pensees","tag-grande-sensibilite-emotionnelle","tag-jeunes-suicidaires","tag-lumiere-au-bout-du-tunnel","tag-situations-conflictuelles","tag-sources-dinspiration","tag-veritable-objectif-personnel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Crise Suicidaire... - Autre Conscience, Autre Monde<\/title>\n<meta name=\"description\" content=\"Je ne pouvais contr\u00f4ler cette pens\u00e9e&quot;, ou bien encore &quot;Quelque chose ou quelqu&#039;un me disait de me suicider&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Crise Suicidaire... - Autre Conscience, Autre Monde\" \/>\n<meta property=\"og:description\" content=\"Je ne pouvais contr\u00f4ler cette pens\u00e9e&quot;, ou bien encore &quot;Quelque chose ou quelqu&#039;un me disait de me suicider&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Autre Conscience, Autre Monde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/claude.acam\/\" \/>\n<meta property=\"article:published_time\" content=\"1997-02-09T15:21:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-15T20:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael AR.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael AR.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\"},\"author\":{\"name\":\"Michael AR.\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/610af0118294f40e0fdf1b02e7741312\"},\"headline\":\"La Crise Suicidaire&#8230;\",\"datePublished\":\"1997-02-09T15:21:49+00:00\",\"dateModified\":\"2026-02-15T20:32:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\"},\"wordCount\":1474,\"publisher\":{\"@id\":\"https:\/\/www.ac-am.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg\",\"keywords\":[\"\u00e9nergie n\u00e9gative\",\"entit\u00e9s d\u00e9sincarn\u00e9es\",\"\u00eatres humains\",\"formes pens\u00e9es\",\"grande sensibilit\u00e9 \u00e9motionnelle\",\"jeunes suicidaires\",\"lumi\u00e8re au bout du tunnel\",\"situations conflictuelles\",\"sources d'inspiration\",\"v\u00e9ritable objectif personnel\"],\"articleSection\":[\"1997 \u2013 MORT\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\",\"url\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\",\"name\":\"La Crise Suicidaire... - Autre Conscience, Autre Monde\",\"isPartOf\":{\"@id\":\"https:\/\/www.ac-am.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg\",\"datePublished\":\"1997-02-09T15:21:49+00:00\",\"dateModified\":\"2026-02-15T20:32:52+00:00\",\"description\":\"Je ne pouvais contr\u00f4ler cette pens\u00e9e\\\", ou bien encore \\\"Quelque chose ou quelqu'un me disait de me suicider\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage\",\"url\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg\",\"contentUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"La Crise Suicidaire fabriqu\u00e9e par l'IA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ac-am.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Crise Suicidaire&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ac-am.fr\/#website\",\"url\":\"https:\/\/www.ac-am.fr\/\",\"name\":\"Autre Conscience, Autre Monde\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ac-am.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ac-am.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ac-am.fr\/#organization\",\"name\":\"Autre Conscience, Autre Monde\",\"url\":\"https:\/\/www.ac-am.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif\",\"contentUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif\",\"width\":370,\"height\":65,\"caption\":\"Autre Conscience, Autre Monde\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/claude.acam\/\",\"https:\/\/www.youtube.com\/user\/consciencemonde\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/610af0118294f40e0fdf1b02e7741312\",\"name\":\"Michael AR.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a2712fa8809ce1ff4b184f8c9a79444d94bb8b1da253150760a0861ae31b8ee?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a2712fa8809ce1ff4b184f8c9a79444d94bb8b1da253150760a0861ae31b8ee?s=96&d=identicon&r=g\",\"caption\":\"Michael AR.\"},\"url\":\"https:\/\/www.ac-am.fr\/index.php\/author\/michael-ar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Crise Suicidaire... - Autre Conscience, Autre Monde","description":"Je ne pouvais contr\u00f4ler cette pens\u00e9e\", ou bien encore \"Quelque chose ou quelqu'un me disait de me suicider\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/","og_locale":"fr_FR","og_type":"article","og_title":"La Crise Suicidaire... - Autre Conscience, Autre Monde","og_description":"Je ne pouvais contr\u00f4ler cette pens\u00e9e\", ou bien encore \"Quelque chose ou quelqu'un me disait de me suicider\".","og_url":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/","og_site_name":"Autre Conscience, Autre Monde","article_publisher":"https:\/\/fr-fr.facebook.com\/claude.acam\/","article_published_time":"1997-02-09T15:21:49+00:00","article_modified_time":"2026-02-15T20:32:52+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg","type":"image\/jpeg"}],"author":"Michael AR.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael AR.","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#article","isPartOf":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/"},"author":{"name":"Michael AR.","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/610af0118294f40e0fdf1b02e7741312"},"headline":"La Crise Suicidaire&#8230;","datePublished":"1997-02-09T15:21:49+00:00","dateModified":"2026-02-15T20:32:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/"},"wordCount":1474,"publisher":{"@id":"https:\/\/www.ac-am.fr\/#organization"},"image":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg","keywords":["\u00e9nergie n\u00e9gative","entit\u00e9s d\u00e9sincarn\u00e9es","\u00eatres humains","formes pens\u00e9es","grande sensibilit\u00e9 \u00e9motionnelle","jeunes suicidaires","lumi\u00e8re au bout du tunnel","situations conflictuelles","sources d'inspiration","v\u00e9ritable objectif personnel"],"articleSection":["1997 \u2013 MORT"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/","url":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/","name":"La Crise Suicidaire... - Autre Conscience, Autre Monde","isPartOf":{"@id":"https:\/\/www.ac-am.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage"},"image":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg","datePublished":"1997-02-09T15:21:49+00:00","dateModified":"2026-02-15T20:32:52+00:00","description":"Je ne pouvais contr\u00f4ler cette pens\u00e9e\", ou bien encore \"Quelque chose ou quelqu'un me disait de me suicider\".","breadcrumb":{"@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#primaryimage","url":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg","contentUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/1997\/02\/la_crise_suicidaire_par_IA.jpg","width":1024,"height":1024,"caption":"La Crise Suicidaire fabriqu\u00e9e par l'IA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ac-am.fr\/index.php\/1997\/02\/09\/la-crise-suicidaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ac-am.fr\/"},{"@type":"ListItem","position":2,"name":"La Crise Suicidaire&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.ac-am.fr\/#website","url":"https:\/\/www.ac-am.fr\/","name":"Autre Conscience, Autre Monde","description":"","publisher":{"@id":"https:\/\/www.ac-am.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ac-am.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ac-am.fr\/#organization","name":"Autre Conscience, Autre Monde","url":"https:\/\/www.ac-am.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif","contentUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif","width":370,"height":65,"caption":"Autre Conscience, Autre Monde"},"image":{"@id":"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/claude.acam\/","https:\/\/www.youtube.com\/user\/consciencemonde"]},{"@type":"Person","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/610af0118294f40e0fdf1b02e7741312","name":"Michael AR.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a2712fa8809ce1ff4b184f8c9a79444d94bb8b1da253150760a0861ae31b8ee?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a2712fa8809ce1ff4b184f8c9a79444d94bb8b1da253150760a0861ae31b8ee?s=96&d=identicon&r=g","caption":"Michael AR."},"url":"https:\/\/www.ac-am.fr\/index.php\/author\/michael-ar\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1751"}],"version-history":[{"count":4,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions"}],"predecessor-version":[{"id":5391,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions\/5391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/media\/5392"}],"wp:attachment":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}