{"id":2334,"date":"2000-06-04T21:07:08","date_gmt":"2000-06-04T20:07:08","guid":{"rendered":"https:\/\/www.ac-am.fr\/?p=2334"},"modified":"2015-12-18T14:45:39","modified_gmt":"2015-12-18T13:45:39","slug":"la-naissance-de-la-forme-humaine","status":"publish","type":"post","link":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/","title":{"rendered":"La naissance de la forme humaine."},"content":{"rendered":"<div id=\"pouvoir\" style=\"background-attachment: fixed; border: 2px solid #dfe6de; border-radius: 10px; opacity: 0.90;\">\n<table class=\"aligncenter\" style=\"width: 600px;\" border=\"0\">\n<tbody>\n<tr>\n<td>\n<table class=\"aligncenter\" style=\"width: 567px; height: 190px;\" border=\"0\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\" alt=\"\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/retepouv.gif\" alt=\"R\u00e9flexions et T\u00e9moignages\" width=\"380\" height=\"100\" border=\"0\" \/><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/cal2000.gif\" alt=\"Ann\u00e9e 2000\" width=\"150\" height=\"100\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\" alt=\"\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"aligncenter\" style=\"width: 590px;\" border=\"0\">\n<tbody>\n<tr>\n<td><a name=\"Claude02B_pouv00_01\"><\/a><b class=\"ntitre1\">La naissance de la forme humaine.<\/b><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\" alt=\"\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Un humain tire sa formation du corps de sa m\u00e8re. Des mol\u00e9cules physiques, issues de la m\u00e8re, s&rsquo;assemblent en un ensemble mat\u00e9riellement coh\u00e9rent apte \u00e0 vivre, \u00e0 terme, dans un environnement instinctif. La m\u00e8re fait tout ce qui est en son pouvoir pour que son enfant naisse conforme car elle sait qu&rsquo;elle souffrira les angoisses d&rsquo;une venue non-conforme. Si l&rsquo;enfant na\u00eet conforme aux lois naturelles, il peut esp\u00e9rer une progression normale dans les chemins de la vie. S&rsquo;il na\u00eet non-conforme, la mort, suppression de mati\u00e8re, l&rsquo;\u00e9limine ou sa perspective via les instincts parentaux pousse ses parents \u00e0 le soigner.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Un esprit tire sa formation de la vie quotidienne d&rsquo;un humain. Des mol\u00e9cules m\u00e9taphysiques &#8211; des images abstraites de la vie et de l&rsquo;environnement de l&rsquo;humain &#8211; s&rsquo;assemblent en un ensemble spirituellement coh\u00e9rent apte \u00e0 vivre, \u00e0 terme, dans un environnement intelligent. L&rsquo;humain doit tout faire pour que l&rsquo;esprit, issu de sa propre vie, na\u00eesse conforme aux lois spirituelles car il se verra, \u00e0 la mort de son corps physique qui correspond \u00e0 la naissance de l&rsquo;esprit, vivre dans la vie de celui-ci.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Le f\u0153tus d&rsquo;esprit ne participe pas \u00e0 la vie quotidienne de son h\u00f4te humain ; Il est en gestation. Il ne peut ni l&rsquo;influencer ni le persuader. Sa seule activit\u00e9 est la m\u00e9morisation d&rsquo;images de la vie de l&rsquo;humain, le conforme spirituellement comme le non-conforme, sans rien arbitrer. Ces images seront les bases de sa future vie spirituelle.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> La mort du corps physique de l&rsquo;humain correspond \u00e0 la naissance de l&rsquo;esprit. D\u00e8s lors, ce nouvel \u00eatre spirituel entre dans une nature intelligente pour l&rsquo;\u00e9ternit\u00e9 ; Les images m\u00e9moris\u00e9es au cours de la vie humaine sont les bases de son anatomie. S&rsquo;il na\u00eet spirituellement viable ; Si la vie humaine gestatrice et son environnement l&rsquo;a model\u00e9 de fa\u00e7on appropri\u00e9e, le nouvel esprit peut esp\u00e9rer une existence \u00e0 tendance extasique. S&rsquo;il na\u00eet non-conforme, les lieux angoissants l&rsquo;obligeront \u00e0 s&rsquo;am\u00e9liorer. Par un processus d\u00e9fiant les lois mat\u00e9rielles et spirituelles, l&rsquo;humain gestateur se voit, apr\u00e8s la mort totale de son corps physique, vivre \u00e9ternellement dans la vie de l&rsquo;esprit issue de son propre comportement. Mieux vaut pour l&rsquo;humain que son esprit naisse conforme aux lois spirituelles ; La mort, suppression de mati\u00e8re et de souffrance, n&rsquo;existe pas dans le Spirituel. Seul r\u00e8gne la d\u00e9mesure de l&rsquo;extr\u00e9mit\u00e9 angoisse pour forcer \u00e0 l&rsquo;am\u00e9lioration. Un comportement humain de paix et de responsabilit\u00e9 produit des images adapt\u00e9es \u00e0 la conformit\u00e9 d&rsquo;un esprit.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Par un comportement de paix et de responsabilit\u00e9, un humain, d&rsquo;une part per\u00e7oit un contr\u00f4le efficace de son intelligence par l&rsquo;interm\u00e9diaire d&rsquo;un partenaire esprit qui lui \u00e9vitera les \u00e9carts d&rsquo;un comportement intelligent incontr\u00f4l\u00e9 et d&rsquo;autre part, il se b\u00e2tit un patrimoine spirituel solide dans la gestation d&rsquo;un esprit qui deviendra son h\u00e9bergeur pour l&rsquo;\u00e9ternit\u00e9.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Tout est naturellement ajust\u00e9 pour que l&rsquo;Humain ait un comportement de paix et de responsabilit\u00e9 envers lui-m\u00eame, envers ses semblables, envers toute la nature ; C&rsquo;est son r\u00f4le dans son environnement ! Il n&rsquo;a pas d&rsquo;autres choix s&rsquo;il veut profiter d&rsquo;une existence physique et m\u00e9taphysique saine.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> L&rsquo;Humain a un r\u00f4le d&rsquo;harmonie dans sa nature. C&rsquo;est son comportement intelligent l&rsquo;outil fondamental d&rsquo;harmonie. L&rsquo;Humain est le summum de la nature mat\u00e9rielle ; C&rsquo;est un mammif\u00e8re omnivore ; Ses bras, affranchis de la marche, sont termin\u00e9s par des mains au pouce oppos\u00e9 aux autres doigts formant une pince.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Cette silhouette debout, ces bras lib\u00e9r\u00e9s, ces appendices insurpassables que sont les mains, toute cette sommit\u00e9 mat\u00e9rielle associ\u00e9e \u00e0 de l&rsquo;intelligence spirituelle font de l&rsquo;Humain un \u00eatre exceptionnel capable de prendre de la mati\u00e8re et de la modeler et d&rsquo;\u00eatre ainsi, \u00e0 moindre \u00e9chelle, l&rsquo;\u00e9gal de la nature qui fa\u00e7onne l&rsquo;environnement.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Le pi\u00e8ge pour l&rsquo;Humain est d&rsquo;entrer en concurrence avec la nature. Ses capacit\u00e9s, certes, pr\u00eatent \u00e0 la d\u00e9rive mais il n&rsquo;est pas \u00ab\u00a0construit\u00a0\u00bb pour cela. Il n&rsquo;a aucune chance de salut en ce sens ; Les proportions sont d\u00e9mesur\u00e9es ! Son r\u00f4le, dans son environnement, est de veiller au fonctionnement normal de la nature. La nature a mis des lois parfaites d\u00e8s le d\u00e9part. Ces lois influent sur le comportement instinctif des esp\u00e8ces. Il est tout \u00e0 fait possible qu&rsquo;une esp\u00e8ce animale ou v\u00e9g\u00e9tale se d\u00e9veloppe anormalement tout en respectant les lois naturelles ; Dans ce cas, la nature ne peut rien faire. Cette race, par son d\u00e9veloppement anarchique, tend \u00e0 annuler la biodiversit\u00e9 en ne laissant, dans son environnement, que ce qui lui est n\u00e9cessaire pour vivre. Sans une intervention humaine, sans cette sommit\u00e9 morphologique intelligente capable de prendre, sciemment, de la mati\u00e8re et de la modeler c&rsquo;en est fait de l&rsquo;harmonie sur la plan\u00e8te.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> Les humains et les esprits ont le m\u00eame r\u00f4le dans leur environnement.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> L&rsquo;Humain est outill\u00e9 pour ma\u00eetriser : Son physique et son intelligence lui fournissent des capacit\u00e9s exceptionnelles pour intervenir, \u00e0 bon escient, dans un univers de mati\u00e8re.<\/span><\/p>\n<p> <span class=\"gmoyen\"><img decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/12\/ball_vc.gif\" alt=\"\" border=\"0\" \/> L&rsquo;Esprit est aussi le summum de sa nature : Son anatomie abstraite n&rsquo;est pas fig\u00e9e dans l&rsquo;\u00e9ternit\u00e9. Elle se r\u00e9g\u00e9n\u00e8re sans cesse dans le Mat\u00e9riel au travers de la symbiose avec l&rsquo;Humain qui la font \u00e9voluer en instinct et l&rsquo;instinct est surpuissant dans un environnement intelligent.<\/span><\/p>\n<p> <span class=\"gmoyen\"><i>[<a href=\"boites.htm#Claude02_B\">Claude De B. &#8211; le 04-06-00<\/a>]<\/i><\/span><a href=\"http:\/\/www.ac-am.fr\/index.php\/claude-de-b\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/ecrits2.gif\" alt=\"\" width=\"50\" height=\"36\" border=\"0\" hspace=\"10\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"big\";var hupso_image_folder_url = \"\";var hupso_url_t=\"\";var hupso_title_t=\"La%20naissance%20de%20la%20forme%20humaine.\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>La naissance de la forme humaine. Un humain tire sa formation du corps de sa&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","hentry","category-2000-pouvoirs-caches"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La naissance de la forme humaine. - Autre Conscience, Autre Monde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La naissance de la forme humaine. - Autre Conscience, Autre Monde\" \/>\n<meta property=\"og:description\" content=\"La naissance de la forme humaine. Un humain tire sa formation du corps de sa...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Autre Conscience, Autre Monde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/claude.acam\/\" \/>\n<meta property=\"article:published_time\" content=\"2000-06-04T20:07:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-18T13:45:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\" \/>\n<meta name=\"author\" content=\"Claude De B.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claude De B.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\"},\"author\":{\"name\":\"Claude De B.\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/aa3783f7a7ae44b4088637b07a254fc1\"},\"headline\":\"La naissance de la forme humaine.\",\"datePublished\":\"2000-06-04T20:07:08+00:00\",\"dateModified\":\"2015-12-18T13:45:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\"},\"wordCount\":985,\"publisher\":{\"@id\":\"https:\/\/www.ac-am.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\",\"articleSection\":[\"2000 \u2013 POUVOIRS CACH\u00c9S\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\",\"url\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\",\"name\":\"La naissance de la forme humaine. - Autre Conscience, Autre Monde\",\"isPartOf\":{\"@id\":\"https:\/\/www.ac-am.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\",\"datePublished\":\"2000-06-04T20:07:08+00:00\",\"dateModified\":\"2015-12-18T13:45:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage\",\"url\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\",\"contentUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif\",\"width\":550,\"height\":7,\"caption\":\"barre marron\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ac-am.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La naissance de la forme humaine.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ac-am.fr\/#website\",\"url\":\"https:\/\/www.ac-am.fr\/\",\"name\":\"Autre Conscience, Autre Monde\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ac-am.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ac-am.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ac-am.fr\/#organization\",\"name\":\"Autre Conscience, Autre Monde\",\"url\":\"https:\/\/www.ac-am.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif\",\"contentUrl\":\"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif\",\"width\":370,\"height\":65,\"caption\":\"Autre Conscience, Autre Monde\"},\"image\":{\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/claude.acam\/\",\"https:\/\/www.youtube.com\/user\/consciencemonde\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/aa3783f7a7ae44b4088637b07a254fc1\",\"name\":\"Claude De B.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ac-am.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0473ffb539479004f1e2b0d44df778979f003fced9c54bb949d431391031dd52?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0473ffb539479004f1e2b0d44df778979f003fced9c54bb949d431391031dd52?s=96&d=identicon&r=g\",\"caption\":\"Claude De B.\"},\"url\":\"https:\/\/www.ac-am.fr\/index.php\/author\/claude-de-b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La naissance de la forme humaine. - Autre Conscience, Autre Monde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/","og_locale":"fr_FR","og_type":"article","og_title":"La naissance de la forme humaine. - Autre Conscience, Autre Monde","og_description":"La naissance de la forme humaine. Un humain tire sa formation du corps de sa...","og_url":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/","og_site_name":"Autre Conscience, Autre Monde","article_publisher":"https:\/\/fr-fr.facebook.com\/claude.acam\/","article_published_time":"2000-06-04T20:07:08+00:00","article_modified_time":"2015-12-18T13:45:39+00:00","og_image":[{"url":"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif","type":"","width":"","height":""}],"author":"Claude De B.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Claude De B.","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#article","isPartOf":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/"},"author":{"name":"Claude De B.","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/aa3783f7a7ae44b4088637b07a254fc1"},"headline":"La naissance de la forme humaine.","datePublished":"2000-06-04T20:07:08+00:00","dateModified":"2015-12-18T13:45:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/"},"wordCount":985,"publisher":{"@id":"https:\/\/www.ac-am.fr\/#organization"},"image":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif","articleSection":["2000 \u2013 POUVOIRS CACH\u00c9S"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/","url":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/","name":"La naissance de la forme humaine. - Autre Conscience, Autre Monde","isPartOf":{"@id":"https:\/\/www.ac-am.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage"},"image":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif","datePublished":"2000-06-04T20:07:08+00:00","dateModified":"2015-12-18T13:45:39+00:00","breadcrumb":{"@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#primaryimage","url":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif","contentUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/09\/barre_mr.gif","width":550,"height":7,"caption":"barre marron"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ac-am.fr\/index.php\/2000\/06\/04\/la-naissance-de-la-forme-humaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ac-am.fr\/"},{"@type":"ListItem","position":2,"name":"La naissance de la forme humaine."}]},{"@type":"WebSite","@id":"https:\/\/www.ac-am.fr\/#website","url":"https:\/\/www.ac-am.fr\/","name":"Autre Conscience, Autre Monde","description":"","publisher":{"@id":"https:\/\/www.ac-am.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ac-am.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ac-am.fr\/#organization","name":"Autre Conscience, Autre Monde","url":"https:\/\/www.ac-am.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif","contentUrl":"https:\/\/www.ac-am.fr\/wp-content\/uploads\/2015\/10\/bd_ac_am.gif","width":370,"height":65,"caption":"Autre Conscience, Autre Monde"},"image":{"@id":"https:\/\/www.ac-am.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/claude.acam\/","https:\/\/www.youtube.com\/user\/consciencemonde"]},{"@type":"Person","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/aa3783f7a7ae44b4088637b07a254fc1","name":"Claude De B.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ac-am.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0473ffb539479004f1e2b0d44df778979f003fced9c54bb949d431391031dd52?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0473ffb539479004f1e2b0d44df778979f003fced9c54bb949d431391031dd52?s=96&d=identicon&r=g","caption":"Claude De B."},"url":"https:\/\/www.ac-am.fr\/index.php\/author\/claude-de-b\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":3,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":2337,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions\/2337"}],"wp:attachment":[{"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ac-am.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}